{"id":14229,"date":"2022-07-05T03:52:13","date_gmt":"2022-07-05T03:52:13","guid":{"rendered":"https:\/\/recla.org\/?p=14229"},"modified":"2022-07-14T14:11:38","modified_gmt":"2022-07-14T14:11:38","slug":"claves-para-hacer-un-podcast-educativo","status":"publish","type":"post","link":"https:\/\/recla.org\/en\/blog\/claves-para-hacer-un-podcast-educativo\/","title":{"rendered":"Podcast \u201cLa escucha elegida\u201d. Claves para hacer un Podcast Educativo"},"content":{"rendered":"<p>El mundo del podcasting est\u00e1 en su mejor momento. Seg\u00fan datos publicados en abril 2022 por la Statista Global Consumer Survey[1] sigue en aumento el n\u00famero de oyentes de podcast a nivel mundial. Esta encuestadora que estudia su consumo desde 2017, y se proyecta analizarlo hasta 2026, concluy\u00f3 al cierre de 2020, que: \u201caproximadamente 533 millones de personas escuchaban podcasts en el mundo. Esta cifra, que supuso un incremento de 125 millones con respecto al a\u00f1o previo, supone el mantenimiento de la tendencia positiva que este formato viene experimentado recientemente. Adem\u00e1s, seg\u00fan las previsiones, el n\u00famero de oyentes continuar\u00e1 en aumento en el siguiente quinquenio hasta aproximarse a los 975 millones en 2026\u201d.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #0a0a0a;color:#0a0a0a\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #0a0a0a;color:#0a0a0a\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/recla.org\/en\/blog\/claves-para-hacer-un-podcast-educativo\/#%C2%BFQue_es_un_Podcast_Educativo\" >\u00bfQu\u00e9 es un Podcast Educativo?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/recla.org\/en\/blog\/claves-para-hacer-un-podcast-educativo\/#Claves_para_hacer_un_podcast_Educativo\" >Claves para hacer un podcast Educativo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/recla.org\/en\/blog\/claves-para-hacer-un-podcast-educativo\/#Transformacion_del_aprendizaje\" >Transformaci\u00f3n del aprendizaje<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_un_Podcast_Educativo\"><\/span>\u00bfQu\u00e9 es un Podcast Educativo?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La primera entrada de la palabra Podcast se realiz\u00f3 en un diccionario en el New Oxford American Dictionary en el a\u00f1o 2005, y all\u00ed se defin\u00eda como una grabaci\u00f3n digital de un programa de radio o cualquier formato de audio que se pon\u00eda al libre acceso en Internet para que pudiera ser descargado por todos los usuarios que estuvieran interesados en la tem\u00e1tica que tratara. [2]\n<p>Esta definici\u00f3n aplica a los podcasts educativos en cuanto no cambian los procesos de creaci\u00f3n y forma de consumo, s\u00ed hay diferencias en las tem\u00e1ticas compartidas que se orientan a difundir ideas, aprendizajes, reflexiones de especialistas y buenas pr\u00e1cticas de ense\u00f1anza y aprendizaje.<\/p>\n<p>Dado que el podcast se ha convertido en un formato de consumo de contenidos muy popular, tanto docentes como alumnos conocen su funcionamiento y aprovechan su ubicuidad y facilidad de uso para escucharlos en cualquier momento y lugar tanto en computadoras como en celulares.<\/p>\n<p>De esta forma el podcast ofrece a la educaci\u00f3n una potente alternativa para los docentes que est\u00e1n llevando a las aulas los lenguajes y las nuevas formas de consumo que requiere el necesario cambio educativo.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Claves_para_hacer_un_podcast_Educativo\"><\/span>Claves para hacer un podcast Educativo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ol>\n<li>Cuando pensamos en el podcast como un recurso did\u00e1ctico es clave preguntarse cu\u00e1l es la intencionalidad pedag\u00f3gica y comunicativa que guiar\u00e1 su proceso de producci\u00f3n. Entender que el podcast es parte de un dise\u00f1o promueve una buena pr\u00e1ctica did\u00e1ctica. Si tenemos en cuenta que el podcast se consume en su gran mayor\u00eda desde el celular, con auriculares y on demand, podemos tomar mejores decisiones en funci\u00f3n de cu\u00e1ndo, c\u00f3mo y para qu\u00e9.<\/li>\n<li>Selecci\u00f3n del tema. Una de las caracter\u00edsticas de las narrativas de este milenio tiene que ver con la concisi\u00f3n. Leemos, vemos y escuchamos mensajes o discursos breves. Si un audio de WhatsApp de 3 minutos puede resultarnos largo, imaginen sostener la atenci\u00f3n del oyente\/estudiante durante 20 o 30 minutos. Seleccionar el tema, poner foco en lo importante, entrenar nuestra capacidad de s\u00edntesis y jerarquizar las ideas es una instancia clave del momento de producci\u00f3n.<\/li>\n<li>Aprender a guionar. El guion es nuestro GPS. Un mapa de ruta. Nos muestra el camino a seguir y la manera en que puedo ordenar las ideas, y fundamentalmente integrar los componentes del lenguaje sonoro: la palabra, la m\u00fasica, los efectos y los silencios. Muchas son las diferencias entre la escritura para ser le\u00edda, y lo que llamamos \u201cescribir para el o\u00eddo\u201d. El guion es la estructura general, generalmente organizado en segmentos, que da cuenta del podcast como unidad de sentido y significaci\u00f3n. Apelar s\u00f3lo al o\u00eddo como canal de percepci\u00f3n requiere que aprendamos a construir un mensaje oral desde estrategias m\u00e1s espec\u00edficas que logren sostener la atenci\u00f3n de la audiencia.<\/li>\n<li>Animarse a comunicar con otro tipo de lenguajes: la voz, la palabra, y tambi\u00e9n la m\u00fasica, los efectos y el silencio. Una de las potencias del podcast es la posibilidad de disparar y provocar emociones en quien escucha. La voz humana, su melod\u00eda, cadencias, tonos y matices, transmiten emociones. Y es ah\u00ed donde descubrimos un mundo de posibilidades. Si a ello le sumamos el valor de la m\u00fasica como lenguaje universal podemos concebir el acto educativo como un acto comunicativo que atraviesa el cuerpo y el coraz\u00f3n de los estudiantes.<\/li>\n<li>Calidad de sonido. Existen muchas aplicaciones que nos permiten grabar podcast desde el propio celular. Es importante tener en cuenta cuestiones b\u00e1sicas de calidad de grabaci\u00f3n: evitar ruidos de fondo, controlar vol\u00famenes para que la m\u00fasica no tape a la voz, y respetar tiempos, entre otros. Una buena calidad nos asegura una efectiva recepci\u00f3n del mensaje. Animarse a explorar apps y opciones en l\u00ednea es parte del proceso creativo y m\u00e1s simple de lo que parece.<\/li>\n<\/ol>\n<h2><span class=\"ez-toc-section\" id=\"Transformacion_del_aprendizaje\"><\/span>Transformaci\u00f3n del aprendizaje<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Un podcast educativo tiene por objetivo compartir conocimientos para ayudar a otras personas a conocerlos e interiorizarlos. El podcast como c\u00e1psula sonora impulsa procesos de pensamiento, pero, fundamentalmente, nos ayuda a educar con emoci\u00f3n.<\/p>\n<p>Difunde ideas y saberes y los expande, como tantas otras tendencias culturales que pueden viralizarse para difundir experiencias e ideas y servir de inspiraci\u00f3n.<\/p>\n<p>Este es un gran reto al que se suma la Comisi\u00f3n de Educaci\u00f3n Continua Virtual de RECLA. Educar en formatos h\u00edbridos es el eje a partir del cual compartimos las producciones de esta comisi\u00f3n pensadas con la finalidad de servir a la transformaci\u00f3n del aprendizaje de las unidades de EC de la red: https:\/\/www.podnation.co\/show\/retos-y-claves-de-la-gestion-estrategica-de-la-educacion-continua<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/cecilia-pacce-rosato-b81819157\/\" target=\"_blank\" rel=\"noopener nofollow\"><img decoding=\"async\" src=\"https:\/\/recla.org\/wp-content\/uploads\/2020\/08\/linkedin.png\" width=\"18\" height=\"18\" \/> Cecilia Pacce Rosato<\/a><br \/>\nEsp. en Educaci\u00f3n y Tecnologias (FLACSO).<br \/>\nDipl. en Gesti\u00f3n Educativa FLACSO. Dipl. en Neuroaprendizaje UB. Lic. Licenciada en Comunicaci\u00f3n Social y Locutora Nacional.<br \/>\nFue Directora de Carrera durante 10 a\u00f1os en el CUP.<br \/>\nDocente de grado y posgrado en la UBP, UCC, UNC y en el CUP.<br \/>\nInvestigadora del CIADE en Educaci\u00f3n de la UBP.<\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/silvina-grezzi-28777213\/\" target=\"_blank\" rel=\"noopener nofollow\"><img decoding=\"async\" src=\"https:\/\/recla.org\/wp-content\/uploads\/2020\/08\/linkedin.png\" width=\"18\" height=\"18\" \/> Silvina Grezzi<\/a><br \/>\nCoordinadora Innovaci\u00f3n Educativa UBP<br \/>\nCoordinadora Comisi\u00f3n de Educaci\u00f3n Continua Virtual de la Red de Educaci\u00f3n Continua de Latinoam\u00e9rica y Europa.<br \/>\nMaestrando en Tecnolog\u00eda Educativa UBA.<br \/>\nInvestigadora del CIADE en Educaci\u00f3n de la UBP. Participa en proyectos interdisciplinarios desarrollados en conjunto con las universidades Tecnol\u00f3gico de Monterrey (M\u00e9xico) e Instituto de Tecnolog\u00eda Holon (Israel).<\/p>\n<p>&nbsp;<\/p>\n[1] https:\/\/es.statista.com\/estadisticas\/626499\/oyentes-de-podcast-a-nivel-mundial\/<br \/>\n[2] Solano Fern\u00e1ndez, Isabel M\u00aa; Sanchez Vera, M\u00aa Mar APRENDIENDO EN CUALQUIER LUGAR: EL PODCAST EDUCATIVO Pixel-Bit. Revista de Medios y Educaci\u00f3n, n\u00fam. 36, enero, 2010, pp. 125-139 Universidad de Sevilla Sevilla, Espa\u00f1a<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mundo del podcasting est\u00e1 en su mejor momento seg\u00fan datos publicados en abril 2022 por la Statista Global Consumer Survey<\/p>","protected":false},"author":2404,"featured_media":14232,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"categories":[111,200],"tags":[286],"class_list":["post-14229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-docencia-en-educacion-continua","tag-docencia-en-educacion-continua"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Claves para hacer un Podcast Educativo &#8211; RECLA<\/title>\n<meta name=\"description\" content=\"El mundo del podcasting est\u00e1 en su mejor momento, y desde RECLA extendemos la Educaci\u00f3n Continua por este medio. \u00a1Conoce nuestros secretos!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recla.org\/en\/blog\/claves-para-hacer-un-podcast-educativo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Claves para hacer un Podcast Educativo\" \/>\n<meta property=\"og:description\" content=\"El mundo del podcasting est\u00e1 en su mejor momento, y desde RECLA extendemos la Educaci\u00f3n Continua por este medio. \u00a1Conoce nuestros secretos!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recla.org\/en\/blog\/claves-para-hacer-un-podcast-educativo\/\" \/>\n<meta property=\"og:site_name\" content=\"RECLA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/recla.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-05T03:52:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-14T14:11:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recla.org\/wp-content\/uploads\/2022\/07\/claves-para-hacer-un-podcast-educativo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1801\" \/>\n\t<meta property=\"og:image:height\" content=\"1021\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Claves para hacer un Podcast Educativo\" \/>\n<meta name=\"twitter:description\" content=\"El mundo del podcasting est\u00e1 en su mejor momento, y desde RECLA extendemos la Educaci\u00f3n Continua por este medio. \u00a1Conoce nuestros secretos!\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/recla.org\/wp-content\/uploads\/2022\/07\/claves-para-hacer-un-podcast-educativo.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@RECLAorg\" \/>\n<meta name=\"twitter:site\" content=\"@RECLAorg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Podcast \u201cLa escucha elegida\u201d. Claves para hacer un Podcast Educativo\",\"datePublished\":\"2022-07-05T03:52:13+00:00\",\"dateModified\":\"2022-07-14T14:11:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/\"},\"wordCount\":1088,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/recla.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/claves-para-hacer-un-podcast-educativo.jpg\",\"keywords\":[\"Docencia en educaci\u00f3n continua\"],\"articleSection\":[\"Blog\",\"Docencia en educaci\u00f3n continua\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/\",\"url\":\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/\",\"name\":\"Claves para hacer un Podcast Educativo &#8211; RECLA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recla.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/claves-para-hacer-un-podcast-educativo.jpg\",\"datePublished\":\"2022-07-05T03:52:13+00:00\",\"dateModified\":\"2022-07-14T14:11:38+00:00\",\"description\":\"El mundo del podcasting est\u00e1 en su mejor momento, y desde RECLA extendemos la Educaci\u00f3n Continua por este medio. \u00a1Conoce nuestros secretos!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/claves-para-hacer-un-podcast-educativo.jpg\",\"contentUrl\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/claves-para-hacer-un-podcast-educativo.jpg\",\"width\":1801,\"height\":1021,\"caption\":\"Claves para hacer un podcast Educativo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/claves-para-hacer-un-podcast-educativo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/recla.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast \u201cLa escucha elegida\u201d. Claves para hacer un Podcast Educativo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recla.org\\\/#website\",\"url\":\"https:\\\/\\\/recla.org\\\/\",\"name\":\"RECLA\",\"description\":\"Red de Educaci\u00f3n Continua de Am\u00e9rica Latina y Europa\",\"publisher\":{\"@id\":\"https:\\\/\\\/recla.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recla.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recla.org\\\/#organization\",\"name\":\"Recla de Educaci\u00f3n continua de Am\u00e9rica Latina y Europa\",\"url\":\"https:\\\/\\\/recla.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/recla.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/logo-recla-2019-google-02.png\",\"contentUrl\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/logo-recla-2019-google-02.png\",\"width\":626,\"height\":626,\"caption\":\"Recla de Educaci\u00f3n continua de Am\u00e9rica Latina y Europa\"},\"image\":{\"@id\":\"https:\\\/\\\/recla.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/recla.org\\\/\",\"https:\\\/\\\/x.com\\\/RECLAorg\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/red-de-educaci\u00f3n-continua-de-latam-y-europa-894756148\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCG25tkuOe2YN5913jR_PcpA\"]},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Claves para hacer un Podcast Educativo &#8211; RECLA","description":"El mundo del podcasting est\u00e1 en su mejor momento, y desde RECLA extendemos la Educaci\u00f3n Continua por este medio. \u00a1Conoce nuestros secretos!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recla.org\/en\/blog\/claves-para-hacer-un-podcast-educativo\/","og_locale":"en_US","og_type":"article","og_title":"Claves para hacer un Podcast Educativo","og_description":"El mundo del podcasting est\u00e1 en su mejor momento, y desde RECLA extendemos la Educaci\u00f3n Continua por este medio. \u00a1Conoce nuestros secretos!","og_url":"https:\/\/recla.org\/en\/blog\/claves-para-hacer-un-podcast-educativo\/","og_site_name":"RECLA","article_publisher":"https:\/\/www.facebook.com\/recla.org\/","article_published_time":"2022-07-05T03:52:13+00:00","article_modified_time":"2022-07-14T14:11:38+00:00","og_image":[{"width":1801,"height":1021,"url":"https:\/\/recla.org\/wp-content\/uploads\/2022\/07\/claves-para-hacer-un-podcast-educativo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Claves para hacer un Podcast Educativo","twitter_description":"El mundo del podcasting est\u00e1 en su mejor momento, y desde RECLA extendemos la Educaci\u00f3n Continua por este medio. \u00a1Conoce nuestros secretos!","twitter_image":"https:\/\/recla.org\/wp-content\/uploads\/2022\/07\/claves-para-hacer-un-podcast-educativo.jpg","twitter_creator":"@RECLAorg","twitter_site":"@RECLAorg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/#article","isPartOf":{"@id":"https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/"},"author":{"name":"","@id":""},"headline":"Podcast \u201cLa escucha elegida\u201d. Claves para hacer un Podcast Educativo","datePublished":"2022-07-05T03:52:13+00:00","dateModified":"2022-07-14T14:11:38+00:00","mainEntityOfPage":{"@id":"https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/"},"wordCount":1088,"commentCount":0,"publisher":{"@id":"https:\/\/recla.org\/#organization"},"image":{"@id":"https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/#primaryimage"},"thumbnailUrl":"https:\/\/recla.org\/wp-content\/uploads\/2022\/07\/claves-para-hacer-un-podcast-educativo.jpg","keywords":["Docencia en educaci\u00f3n continua"],"articleSection":["Blog","Docencia en educaci\u00f3n continua"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/","url":"https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/","name":"Claves para hacer un Podcast Educativo &#8211; RECLA","isPartOf":{"@id":"https:\/\/recla.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/#primaryimage"},"image":{"@id":"https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/#primaryimage"},"thumbnailUrl":"https:\/\/recla.org\/wp-content\/uploads\/2022\/07\/claves-para-hacer-un-podcast-educativo.jpg","datePublished":"2022-07-05T03:52:13+00:00","dateModified":"2022-07-14T14:11:38+00:00","description":"El mundo del podcasting est\u00e1 en su mejor momento, y desde RECLA extendemos la Educaci\u00f3n Continua por este medio. \u00a1Conoce nuestros secretos!","breadcrumb":{"@id":"https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/#primaryimage","url":"https:\/\/recla.org\/wp-content\/uploads\/2022\/07\/claves-para-hacer-un-podcast-educativo.jpg","contentUrl":"https:\/\/recla.org\/wp-content\/uploads\/2022\/07\/claves-para-hacer-un-podcast-educativo.jpg","width":1801,"height":1021,"caption":"Claves para hacer un podcast Educativo"},{"@type":"BreadcrumbList","@id":"https:\/\/recla.org\/blog\/claves-para-hacer-un-podcast-educativo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/recla.org\/"},{"@type":"ListItem","position":2,"name":"Podcast \u201cLa escucha elegida\u201d. Claves para hacer un Podcast Educativo"}]},{"@type":"WebSite","@id":"https:\/\/recla.org\/#website","url":"https:\/\/recla.org\/","name":"RECLA","description":"Latin America and Europe Continuing Education Network","publisher":{"@id":"https:\/\/recla.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recla.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/recla.org\/#organization","name":"Recla de Educaci\u00f3n continua de Am\u00e9rica Latina y Europa","url":"https:\/\/recla.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/recla.org\/#\/schema\/logo\/image\/","url":"https:\/\/recla.org\/wp-content\/uploads\/2019\/08\/logo-recla-2019-google-02.png","contentUrl":"https:\/\/recla.org\/wp-content\/uploads\/2019\/08\/logo-recla-2019-google-02.png","width":626,"height":626,"caption":"Recla de Educaci\u00f3n continua de Am\u00e9rica Latina y Europa"},"image":{"@id":"https:\/\/recla.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/recla.org\/","https:\/\/x.com\/RECLAorg","https:\/\/www.linkedin.com\/in\/red-de-educaci\u00f3n-continua-de-latam-y-europa-894756148","https:\/\/www.youtube.com\/channel\/UCG25tkuOe2YN5913jR_PcpA"]},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/posts\/14229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/users\/2404"}],"replies":[{"embeddable":true,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/comments?post=14229"}],"version-history":[{"count":0,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/posts\/14229\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/media\/14232"}],"wp:attachment":[{"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/media?parent=14229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/categories?post=14229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/tags?post=14229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}