{"id":7481,"date":"2020-04-03T15:16:20","date_gmt":"2020-04-03T15:16:20","guid":{"rendered":"https:\/\/recla.org\/?p=7481"},"modified":"2021-12-20T19:33:06","modified_gmt":"2021-12-20T19:33:06","slug":"consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase","status":"publish","type":"post","link":"https:\/\/recla.org\/en\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/","title":{"rendered":"Consideraciones para realizar una video clase"},"content":{"rendered":"<p>A causa del coronavirus muchos necesitan adaptar sus clases a nuevos formatos. Una manera muy efectiva de acercar a los alumnos contenidos, informaci\u00f3n, explicaciones y apoyo es mediante clases en vivo. Estos encuentros virtuales no son instancias improvisadas. Requieren de una buena organizaci\u00f3n previa en aspectos t\u00e9cnicos y de contenido, as\u00ed como tambi\u00e9n en cuestiones relativas al espacio f\u00edsico y de gesti\u00f3n.<\/p>\n<p>Desde RECLA venimos trabajando activamente con clases en vivo desde el Ciclo de Conferencias Internacionales Virtuales para acercar a nuestros asociados, disertantes y contenidos de calidad, que enriquezcan sus conocimientos, procedimientos y gestiones acad\u00e9micas.<\/p>\n<p>La pandemia del COVID-19 ha provocado una gran demanda de consultas y por ello les acercamos esta lista de acciones a tener en cuenta, fruto de nuestra vasta experiencia.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Index<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #0a0a0a;color:#0a0a0a\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #0a0a0a;color:#0a0a0a\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/recla.org\/en\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#Previo_a_la_clase\" >Previo a la clase<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/recla.org\/en\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#Durante_la_Clase\" >Durante la Clase<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/recla.org\/en\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#Despues_de_la_Clase\" >Despu\u00e9s de la Clase<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/recla.org\/en\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#Comision_de_Educacion_Continua_Virtual\" >Comisi\u00f3n de Educaci\u00f3n Continua Virtual.<\/a><\/li><\/ul><\/nav><\/div>\n<h4><span class=\"ez-toc-section\" id=\"Previo_a_la_clase\"><\/span>Previo a la clase<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><strong>\u00a0<\/strong><strong>Prueba t\u00e9cnica entre disertante, t\u00e9cnico y moderador<\/strong><\/p>\n<ul>\n<li>Tener disponible su presentaci\u00f3n (puede ser power point), dise\u00f1ada teniendo en cuenta la duraci\u00f3n de la exposici\u00f3n (se sugiere no sea mayor a 35\/45 minutos).\n<ul>\n<li>Recuerde utilizar en su presentaci\u00f3n im\u00e1genes que puedan ampliarse sin perder calidad y un tama\u00f1o de tipograf\u00eda que permita una correcta lectura. Revisar la ortograf\u00eda.<\/li>\n<\/ul>\n<\/li>\n<li>Realizar la prueba t\u00e9cnica para conocer el funcionamiento de la herramienta que utilizar\u00e1 para la clase virtual. Puede ser Adobe Connect, Zoom, etc. Para ello coordine un encuentro con un colaborador o moderador si lo tuviera a fin de probar todas las funcionalidades de la herramienta. Esta instancia es muy importante.<\/li>\n<li>Agende los tel\u00e9fonos de contacto de quien ser\u00e1 su moderando o soporte t\u00e9cnico para recurrir a ellos en caso de tener inconvenientes de conexi\u00f3n a internet.<\/li>\n<li>Buscar una ubicaci\u00f3n bien iluminada, tranquila y con buena conexi\u00f3n a <strong>Iluminar el rostro correctamente <\/strong>es importante porque si se ve demasiado oscuro, puede resultar amenazante y\/o grotesco y si es muy brillante, resultar\u00e1 risible.<\/li>\n<li>Elija un <strong>lugar tranquilo <\/strong>en el que no tenga interrupciones o movimiento detr\u00e1s, esto es importante para mantener la atenci\u00f3n del p\u00fablico. Avise a otras personas que va a estar all\u00ed para que no se produzcan interrupciones y tengan cuidado con los ruidos que pudieran realizar. Cierre las ventanas y las puertas y silencie sus dispositivos m\u00f3viles.<\/li>\n<li>Ingrese al software (puede ser Adobe Connect, Zoom, etc.)<\/li>\n<li>Aseg\u00farese que la <strong>c\u00e1mara est\u00e9 encendida<\/strong>.<\/li>\n<li><strong>Sit\u00fae la c\u00e1mara web a la altura de los ojos <\/strong>en la misma pantalla que vaya a usar para realizar la Hay que tener en cuenta que el \u00e1ngulo de visi\u00f3n no quede ni demasiado alto ni demasiado bajo; lo correcto es mirar directamente a la c\u00e1mara.<\/li>\n<li><strong>Ubique la c\u00e1mara <\/strong>de modo que no tenga de fondo una fuente de luz intensa, como la de una ventana, si la luz del exterior es muy intensa la c\u00e1mara tendr\u00e1 distorsiones y su rostro no se ver\u00e1 adecuadamente. En ese caso, ci\u00e9rrela, oscur\u00e9zcala con cortinas o postigos seg\u00fan tenga.<\/li>\n<li><strong>Encienda su micr\u00f3fono y revise el volumen <\/strong>de modo que no est\u00e9 ni muy alto, ni muy bajo. Sugerencia: utilizar aud\u00edfonos de buena calidad porque captan mejor el audio y reducen los ruidos del<\/li>\n<li>Es importante que practique la presentaci\u00f3n completa antes de la presentaci\u00f3n De esta manera podr\u00e1 comprobar si cumple con el tiempo pautado, c\u00f3mo se ve la informaci\u00f3n en pantalla y realizar los ajustes en caso que sean necesarios.<\/li>\n<\/ul>\n<h4><span class=\"ez-toc-section\" id=\"Durante_la_Clase\"><\/span>Durante la Clase<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li>Ingrese a la sala al menos 10 minutos antes del horario pautado para el webinario.<\/li>\n<li>Aseg\u00farese que la <strong>c\u00e1mara est\u00e9 encendida <\/strong>and <strong>habilitada <\/strong>en el software del webinar.<\/li>\n<li><strong>Con\ufb01gure los ajustes de audio<\/strong>, revise que el micr\u00f3fono est\u00e9 encendido y habilitado en la sala del<\/li>\n<li><strong>Cierre todos los programas <\/strong>que tenga abiertos para que no interrumpan la charla o le quiten datos de conexi\u00f3n.<\/li>\n<li>Ubique cerca de usted un vaso y una botella de <strong>agua<\/strong>.<\/li>\n<li><strong>Tenga cerca un tel\u00e9fono m\u00f3vil o fijo<\/strong>, ambos silenciados, para recurrir a ellos en caso de un imprevisto t\u00e9cnico que lo deje fuera de la sala y sin conexi\u00f3n.<\/li>\n<li>D\u00e9 la bienvenida a sus alumnos, comparta los temas a desarrollar y el tiempo establecido para exposic\u00f3n y preguntas.<\/li>\n<li>Desarrolle su presentaci\u00f3n teniendo en cuenta el <strong>tiempo pautado <\/strong>para la<\/li>\n<li><strong>Est\u00e9 atento a las consultas <\/strong>que pudieran realizarle durante su presentaci\u00f3n, si lo desea puede responderlas en el momento o indicarles que al finalizar su charla habr\u00e1 un espacio de preguntas.<\/li>\n<li>Finalizo el tiempo de exposici\u00f3n y consultas, desp\u00eddase de los participantes y desconecte su c\u00e1mara y micr\u00f3fono.<\/li>\n<\/ul>\n<h4><span class=\"ez-toc-section\" id=\"Despues_de_la_Clase\"><\/span>Despu\u00e9s de la Clase<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li>Se sugiere abrir un espacio para responder las consultas que pudieran surgir, puede ser un foro, un muro de su materia.<\/li>\n<li>Es importante acercar a sus alumnos una encuesta online, puede compartirla al finalizar su charla o enviarla luego por mail por ejemplo.<\/li>\n<\/ul>\n<p>Esperamos que estas recomendaciones sean de utilidad.<\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Comision_de_Educacion_Continua_Virtual\"><\/span>Comisi\u00f3n de Educaci\u00f3n Continua Virtual.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/silvina-grezzi-28777213\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Lic. Grezzi Silvina<\/b><\/a><br \/>\n<span style=\"font-weight: 400;\">Coordinadora Comisi\u00f3n Educaci\u00f3n Continua Virtual RECLA<\/span><br \/>\n<span style=\"font-weight: 400;\">Universidad Blas Pascal<\/span><\/p>\n<p><a href=\"https:\/\/www.linkedin.com\/in\/valeria-moschetta-9b167732\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>Lic. Moschetta Valeria<\/b><\/a><br \/>\n<span style=\"font-weight: 400;\">Coordinadora Comisi\u00f3n Educaci\u00f3n Continua Virtual RECLA<\/span><br \/>\n<span style=\"font-weight: 400;\">Universidad Blas Pascal<\/span><\/p>\n<p>Conozca c\u00f3mo participar en esta comisi\u00f3n <strong><a href=\"https:\/\/recla.org\/en\/actividades\/comisiones-de-trabajo\/\" target=\"_blank\" rel=\"noopener noreferrer\">here<\/a>.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>A causa del coronavirus muchos necesitan adaptar sus clases a nuevos formatos.<\/p>","protected":false},"author":2404,"featured_media":8688,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"categories":[111,200],"tags":[286],"class_list":["post-7481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-docencia-en-educacion-continua","tag-docencia-en-educacion-continua"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Consideraciones para realizar una video clase<\/title>\n<meta name=\"description\" content=\"Recla es una organizaci\u00f3n sin \u00e1nimo de lucro, legalmente constituida en Colombia desde el a\u00f1o 1997.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/recla.org\/en\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consideraciones para realizar una video clase\" \/>\n<meta property=\"og:description\" content=\"Recla es una organizaci\u00f3n sin \u00e1nimo de lucro, legalmente constituida en Colombia desde el a\u00f1o 1997.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/recla.org\/en\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/\" \/>\n<meta property=\"og:site_name\" content=\"RECLA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/recla.org\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-03T15:16:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-20T19:33:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/recla.org\/wp-content\/uploads\/2020\/04\/consideraciones-para-realizar-una-video-clase.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1801\" \/>\n\t<meta property=\"og:image:height\" content=\"1021\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@RECLAorg\" \/>\n<meta name=\"twitter:site\" content=\"@RECLAorg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Consideraciones para realizar una video clase\",\"datePublished\":\"2020-04-03T15:16:20+00:00\",\"dateModified\":\"2021-12-20T19:33:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/\"},\"wordCount\":890,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/recla.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/consideraciones-para-realizar-una-video-clase.png\",\"keywords\":[\"Docencia en educaci\u00f3n continua\"],\"articleSection\":[\"Blog\",\"Docencia en educaci\u00f3n continua\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/\",\"url\":\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/\",\"name\":\"Consideraciones para realizar una video clase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/recla.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/consideraciones-para-realizar-una-video-clase.png\",\"datePublished\":\"2020-04-03T15:16:20+00:00\",\"dateModified\":\"2021-12-20T19:33:06+00:00\",\"description\":\"Recla es una organizaci\u00f3n sin \u00e1nimo de lucro, legalmente constituida en Colombia desde el a\u00f1o 1997.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/#primaryimage\",\"url\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/consideraciones-para-realizar-una-video-clase.png\",\"contentUrl\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/consideraciones-para-realizar-una-video-clase.png\",\"width\":1801,\"height\":1021},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/recla.org\\\/blog\\\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/recla.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consideraciones para realizar una video clase\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/recla.org\\\/#website\",\"url\":\"https:\\\/\\\/recla.org\\\/\",\"name\":\"RECLA\",\"description\":\"Red de Educaci\u00f3n Continua de Am\u00e9rica Latina y Europa\",\"publisher\":{\"@id\":\"https:\\\/\\\/recla.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/recla.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/recla.org\\\/#organization\",\"name\":\"Recla de Educaci\u00f3n continua de Am\u00e9rica Latina y Europa\",\"url\":\"https:\\\/\\\/recla.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/recla.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/logo-recla-2019-google-02.png\",\"contentUrl\":\"https:\\\/\\\/recla.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/logo-recla-2019-google-02.png\",\"width\":626,\"height\":626,\"caption\":\"Recla de Educaci\u00f3n continua de Am\u00e9rica Latina y Europa\"},\"image\":{\"@id\":\"https:\\\/\\\/recla.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/recla.org\\\/\",\"https:\\\/\\\/x.com\\\/RECLAorg\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/red-de-educaci\u00f3n-continua-de-latam-y-europa-894756148\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCG25tkuOe2YN5913jR_PcpA\"]},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Consideraciones para realizar una video clase","description":"Recla es una organizaci\u00f3n sin \u00e1nimo de lucro, legalmente constituida en Colombia desde el a\u00f1o 1997.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/recla.org\/en\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/","og_locale":"en_US","og_type":"article","og_title":"Consideraciones para realizar una video clase","og_description":"Recla es una organizaci\u00f3n sin \u00e1nimo de lucro, legalmente constituida en Colombia desde el a\u00f1o 1997.","og_url":"https:\/\/recla.org\/en\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/","og_site_name":"RECLA","article_publisher":"https:\/\/www.facebook.com\/recla.org\/","article_published_time":"2020-04-03T15:16:20+00:00","article_modified_time":"2021-12-20T19:33:06+00:00","og_image":[{"width":1801,"height":1021,"url":"https:\/\/recla.org\/wp-content\/uploads\/2020\/04\/consideraciones-para-realizar-una-video-clase.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_creator":"@RECLAorg","twitter_site":"@RECLAorg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#article","isPartOf":{"@id":"https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/"},"author":{"name":"","@id":""},"headline":"Consideraciones para realizar una video clase","datePublished":"2020-04-03T15:16:20+00:00","dateModified":"2021-12-20T19:33:06+00:00","mainEntityOfPage":{"@id":"https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/"},"wordCount":890,"commentCount":0,"publisher":{"@id":"https:\/\/recla.org\/#organization"},"image":{"@id":"https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#primaryimage"},"thumbnailUrl":"https:\/\/recla.org\/wp-content\/uploads\/2020\/04\/consideraciones-para-realizar-una-video-clase.png","keywords":["Docencia en educaci\u00f3n continua"],"articleSection":["Blog","Docencia en educaci\u00f3n continua"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/","url":"https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/","name":"Consideraciones para realizar una video clase","isPartOf":{"@id":"https:\/\/recla.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#primaryimage"},"image":{"@id":"https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#primaryimage"},"thumbnailUrl":"https:\/\/recla.org\/wp-content\/uploads\/2020\/04\/consideraciones-para-realizar-una-video-clase.png","datePublished":"2020-04-03T15:16:20+00:00","dateModified":"2021-12-20T19:33:06+00:00","description":"Recla es una organizaci\u00f3n sin \u00e1nimo de lucro, legalmente constituida en Colombia desde el a\u00f1o 1997.","breadcrumb":{"@id":"https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#primaryimage","url":"https:\/\/recla.org\/wp-content\/uploads\/2020\/04\/consideraciones-para-realizar-una-video-clase.png","contentUrl":"https:\/\/recla.org\/wp-content\/uploads\/2020\/04\/consideraciones-para-realizar-una-video-clase.png","width":1801,"height":1021},{"@type":"BreadcrumbList","@id":"https:\/\/recla.org\/blog\/consideraciones-a-tener-en-cuenta-al-momento-de-realizar-una-video-clase\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/recla.org\/"},{"@type":"ListItem","position":2,"name":"Consideraciones para realizar una video clase"}]},{"@type":"WebSite","@id":"https:\/\/recla.org\/#website","url":"https:\/\/recla.org\/","name":"RECLA","description":"Latin America and Europe Continuing Education Network","publisher":{"@id":"https:\/\/recla.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/recla.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/recla.org\/#organization","name":"Recla de Educaci\u00f3n continua de Am\u00e9rica Latina y Europa","url":"https:\/\/recla.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/recla.org\/#\/schema\/logo\/image\/","url":"https:\/\/recla.org\/wp-content\/uploads\/2019\/08\/logo-recla-2019-google-02.png","contentUrl":"https:\/\/recla.org\/wp-content\/uploads\/2019\/08\/logo-recla-2019-google-02.png","width":626,"height":626,"caption":"Recla de Educaci\u00f3n continua de Am\u00e9rica Latina y Europa"},"image":{"@id":"https:\/\/recla.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/recla.org\/","https:\/\/x.com\/RECLAorg","https:\/\/www.linkedin.com\/in\/red-de-educaci\u00f3n-continua-de-latam-y-europa-894756148","https:\/\/www.youtube.com\/channel\/UCG25tkuOe2YN5913jR_PcpA"]},{"@type":"Person","@id":""}]}},"_links":{"self":[{"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/posts\/7481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/users\/2404"}],"replies":[{"embeddable":true,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/comments?post=7481"}],"version-history":[{"count":0,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/posts\/7481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/media\/8688"}],"wp:attachment":[{"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/media?parent=7481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/categories?post=7481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/recla.org\/en\/wp-json\/wp\/v2\/tags?post=7481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}